{"id":17,"count":3,"description":"","link":"https:\/\/energienerds.nl\/index.php\/tag\/homewizard","name":"homewizard","slug":"homewizard","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>homewizard Archieven - energienerds<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"homewizard Archieven - energienerds\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energienerds.nl\/index.php\/tag\/homewizard\" \/>\n<meta property=\"og:site_name\" content=\"energienerds\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/energienerds.nl\\\/index.php\\\/tag\\\/homewizard\",\"url\":\"https:\\\/\\\/energienerds.nl\\\/index.php\\\/tag\\\/homewizard\",\"name\":\"homewizard Archieven - energienerds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energienerds.nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energienerds.nl\\\/index.php\\\/tag\\\/homewizard#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energienerds.nl\\\/index.php\\\/tag\\\/homewizard#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/energienerds.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"homewizard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energienerds.nl\\\/#website\",\"url\":\"https:\\\/\\\/energienerds.nl\\\/\",\"name\":\"Energienerds\",\"description\":\"Jouw gids in slimme energie\",\"publisher\":{\"@id\":\"https:\\\/\\\/energienerds.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/energienerds.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/energienerds.nl\\\/#organization\",\"name\":\"Energienerds\",\"url\":\"https:\\\/\\\/energienerds.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/energienerds.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/energienerds.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo_trans.png\",\"contentUrl\":\"https:\\\/\\\/energienerds.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/logo_trans.png\",\"width\":512,\"height\":512,\"caption\":\"Energienerds\"},\"image\":{\"@id\":\"https:\\\/\\\/energienerds.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@energienerds\",\"https:\\\/\\\/www.instagram.com\\\/energienerds.nl\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/energienerds\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/energienerds.bsky.social\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"homewizard Archieven - energienerds","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"article","og_title":"homewizard Archieven - energienerds","og_url":"https:\/\/energienerds.nl\/index.php\/tag\/homewizard","og_site_name":"energienerds","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/energienerds.nl\/index.php\/tag\/homewizard","url":"https:\/\/energienerds.nl\/index.php\/tag\/homewizard","name":"homewizard Archieven - energienerds","isPartOf":{"@id":"https:\/\/energienerds.nl\/#website"},"breadcrumb":{"@id":"https:\/\/energienerds.nl\/index.php\/tag\/homewizard#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/energienerds.nl\/index.php\/tag\/homewizard#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energienerds.nl\/"},{"@type":"ListItem","position":2,"name":"homewizard"}]},{"@type":"WebSite","@id":"https:\/\/energienerds.nl\/#website","url":"https:\/\/energienerds.nl\/","name":"Energienerds","description":"Jouw gids in slimme energie","publisher":{"@id":"https:\/\/energienerds.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energienerds.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/energienerds.nl\/#organization","name":"Energienerds","url":"https:\/\/energienerds.nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/energienerds.nl\/#\/schema\/logo\/image\/","url":"https:\/\/energienerds.nl\/wp-content\/uploads\/2025\/03\/logo_trans.png","contentUrl":"https:\/\/energienerds.nl\/wp-content\/uploads\/2025\/03\/logo_trans.png","width":512,"height":512,"caption":"Energienerds"},"image":{"@id":"https:\/\/energienerds.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/@energienerds","https:\/\/www.instagram.com\/energienerds.nl","https:\/\/www.linkedin.com\/in\/energienerds\/","https:\/\/bsky.app\/profile\/energienerds.bsky.social"]}]}},"_links":{"self":[{"href":"https:\/\/energienerds.nl\/index.php\/wp-json\/wp\/v2\/tags\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energienerds.nl\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/energienerds.nl\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/energienerds.nl\/index.php\/wp-json\/wp\/v2\/posts?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}